{"id":1970,"date":"2024-02-14T17:51:43","date_gmt":"2024-02-14T16:51:43","guid":{"rendered":"https:\/\/campingarribesdelduero.com\/regulamento-interno\/"},"modified":"2025-05-18T11:08:01","modified_gmt":"2025-05-18T10:08:01","slug":"regulamento-interno","status":"publish","type":"page","link":"https:\/\/campingarribesdelduero.com\/pt-pt\/regulamento-interno\/","title":{"rendered":"Regras de utiliza\u00e7\u00e3o"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1970\" class=\"elementor elementor-1970 elementor-1500\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-643ef10 e-con-full e-flex e-con e-parent\" data-id=\"643ef10\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c50e1b6 elementor-widget elementor-widget-heading\" data-id=\"c50e1b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">regulamento interno do <br> Camping arribes del duero\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81482ce elementor-widget elementor-widget-text-editor\" data-id=\"81482ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Registo de Campismo n.\u00ba: 37\/0023.<\/span><\/p><p><span style=\"font-weight: 400;\">Categoria: 3 estrelas.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-705833e elementor-widget elementor-widget-spacer\" data-id=\"705833e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9d69bd elementor-widget elementor-widget-text-editor\" data-id=\"b9d69bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><b>POL\u00cdTICA DE ADMISS\u00c3O E RETEN\u00c7\u00c3O<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">O&nbsp;  acesso&nbsp;  a&nbsp;  este&nbsp;  acampamento&nbsp;  de&nbsp;  turismo&nbsp;  \u00e9&nbsp;  livre,&nbsp;  sem&nbsp;  mais&nbsp;  restri\u00e7\u00f5es&nbsp;  que&nbsp;  o&nbsp;  derivados&nbsp;  de&nbsp;  o&nbsp;  leis* e estes regulamentos.&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o \u00e9 permitida a entrada a pessoas que tenham sido anteriormente expulsas por viola\u00e7\u00e3o das regras estabelecidas no presente Regulamento ou que n\u00e3o tenham pago voluntariamente por servi\u00e7os anteriormente prestados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A Dire\u00e7\u00e3o do estabelecimento pode solicitar o aux\u00edlio de agentes policiais para proceder \u00e0 expuls\u00e3o dos utentes que violem o presente Regulamento Interno, ou que tentem aceder ou permanecer no estabelecimento com um fim diferente do estabelecido para a sua utiliza\u00e7\u00e3o espec\u00edfica ou pac\u00edfica como estabelecimento tur\u00edstico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o ser\u00e1 permitida a entrada a pessoas que apresentem sinais evidentes de embriaguez ou que tenham consumido subst\u00e2ncias estupefacientes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o \u00e9 permitido o acesso a pessoas que n\u00e3o estejam devidamente registadas como h\u00f3spedes no acampamento tur\u00edstico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No que diz respeito \u00e0s visitas, e a crit\u00e9rio da Dire\u00e7\u00e3o, pode ser autorizada a entrada de familiares e amigos, a pedido do cliente inscrito, por um per\u00edodo de tempo limitado. Estes visitantes devem inscrever-se na Rece\u00e7\u00e3o, apresentando um documento de identidade v\u00e1lido e pagando a taxa estabelecida. Se o tempo acordado for ultrapassado, o visitante ser\u00e1 considerado cliente diurno, e qualquer pagamento pendente ser\u00e1 da responsabilidade do cliente registado no parque de campismo.<\/span><\/p>\n<h3><b>REGISTO DE ENTRADA<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Se as seguintes condi\u00e7\u00f5es n\u00e3o forem cumpridas, n\u00e3o ser\u00e1 permitido o acesso ao parque de campismo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A entrada nos alojamentos do parque de campismo requer a apresenta\u00e7\u00e3o de um documento de identifica\u00e7\u00e3o v\u00e1lido, como o bilhete de identidade, a carta de condu\u00e7\u00e3o ou o passaporte, para al\u00e9m do preenchimento da documenta\u00e7\u00e3o exigida pelas autoridades espanholas em cada momento. Tamb\u00e9m ser\u00e1 necess\u00e1rio preencher o formul\u00e1rio de admiss\u00e3o correspondente. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Todas as pessoas com mais de 14 anos de idade t\u00eam de estar devidamente documentadas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">S\u00e3o aceites os seguintes documentos para a identifica\u00e7\u00e3o do cliente:&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para os espanh\u00f3is: D.N.I., passaporte ou carta de condu\u00e7\u00e3o.&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para os estrangeiros: passaporte, carta ou bilhete de identidade.&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para os estrangeiros residentes em Espanha: autoriza\u00e7\u00e3o de resid\u00eancia espanhola ou bilhete de identidade de estrangeiro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Todos os menores que permane\u00e7am nas nossas instala\u00e7\u00f5es n\u00e3o acompanhados pelos pais ou tutores legais devem ser portadores de um bilhete de identidade ou passaporte v\u00e1lido e apresentar uma autoriza\u00e7\u00e3o escrita assinada pelos pais ou tutores legais, que deve incluir uma fotoc\u00f3pia do bilhete de identidade, passaporte ou carta de condu\u00e7\u00e3o dos pais ou tutores legais do menor.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No campismo:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O hor\u00e1rio de check-in \u00e9 das<\/span> <span style=\"font-weight: 400;\">09:00 \u00e0s 22:00 e o check-out 24 horas ap\u00f3s o check-in.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em Bungalow:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hora de entrada: 15:00 h e hora de sa\u00edda: 12:00 h.<\/span> <span style=\"font-weight: 400;\"> 12:00 h.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n<p><b>POL\u00cdTICA DE RESERVA E CANCELAMENTO<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Entende-se por reserva um pedido de alojamento apresentado \u00e0 empresa pelo cliente antes do in\u00edcio do servi\u00e7o de alojamento tur\u00edstico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A formaliza\u00e7\u00e3o de uma reserva pressup\u00f5e a aceita\u00e7\u00e3o, por parte do cliente, da Pol\u00edtica de Reserva e de Cancelamento, bem como do Regulamento Interno que, em geral, regula a estadia no parque de campismo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As reservas devem ser confirmadas ou recusadas por qualquer sistema ou meio que permita o registo da sua comunica\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O parque de campismo exige aos veraneantes, ou \u00e0 sociedade intermedi\u00e1ria, se for caso disso, um adiantamento do pre\u00e7o, que se entende como sendo por conta do montante resultante dos servi\u00e7os prestados. Este adiantamento corresponde a 50% do montante da reserva. Os restantes 50% do valor da reserva ser\u00e3o pagos no momento do check-in.  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cancelamento de reservas:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se a reserva for cancelada pelo menos 30 dias antes da data de chegada prevista, ser-te-\u00e1 reembolsado o montante total do dep\u00f3sito.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se a reserva for cancelada entre 15 e 30 dias antes da data de chegada prevista, ser-te-\u00e1 reembolsado metade do dep\u00f3sito.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se uma reserva for cancelada menos de 15 dias antes da data de chegada prevista, n\u00e3o ser\u00e1 efectuado qualquer reembolso do dep\u00f3sito.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estas penaliza\u00e7\u00f5es n\u00e3o ser\u00e3o aplic\u00e1veis quando a anula\u00e7\u00e3o da reserva for devida a um caso de for\u00e7a maior, devidamente comprovado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O parque de campismo reembolsar\u00e1 ao cliente a totalidade do montante exigido como dep\u00f3sito aquando da reserva, quando esta for anulada por raz\u00f5es n\u00e3o imput\u00e1veis ao utilizador.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A anula\u00e7\u00e3o da estadia antes da data prevista de partida n\u00e3o d\u00e1 lugar a qualquer reembolso econ\u00f3mico, no que diz respeito aos dias que faltam consumir. A Dire\u00e7\u00e3o decidir\u00e1 a favor do cliente. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o s\u00e3o permitidas altera\u00e7\u00f5es \u00e0 reserva nos 15 dias anteriores \u00e0 data de chegada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Todos os pedidos de altera\u00e7\u00e3o ou cancelamento devem ser efectuados por escrito para o seguinte endere\u00e7o eletr\u00f3nico: info@campingarribesdelduero.com.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n<p><b>PROGRAMAS<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Escrit\u00f3rio de rece\u00e7\u00e3o na \u00e9poca alta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Das 09:00 \u00e0s 22:00 para os procedimentos de registo e de cancelamento de registo.&nbsp;&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Das 09:00 \u00e0s 13:00 e das 16:00 \u00e0s 20:00 para outros assuntos&nbsp;&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Acampa:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Das 09:00 \u00e0s 22:00 para a instala\u00e7\u00e3o de unidades de campismo.&nbsp;&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sil\u00eancio e descanso:&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Das 23:00 \u00e0s 07:00 para o per\u00edodo de sil\u00eancio&nbsp;&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Das 15:00 \u00e0s 17:00 para o per\u00edodo de repouso&nbsp;&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os outros servi\u00e7os e instala\u00e7\u00f5es constam de quadros que se encontram na rece\u00e7\u00e3o e nas instala\u00e7\u00f5es correspondentes.&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante o per\u00edodo de descanso, pede-se aos clientes que evitem qualquer tipo de ru\u00eddo, como vozes ou discuss\u00f5es. Durante estas horas, o sil\u00eancio ser\u00e1 intensificado, proibindo a circula\u00e7\u00e3o de ve\u00edculos dentro do recinto, bem como a montagem ou desmontagem das unidades de campismo. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n<p><b>ACAMPAMENTO<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Os utilizadores devem instalar-se na parcela ou na zona designada no momento da admiss\u00e3o. Qualquer mudan\u00e7a de local deve ser previamente autorizada. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">S\u00f3 \u00e9 permitida a instala\u00e7\u00e3o dos artigos que tenham sido registados no momento da inscri\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Caso o cliente pretenda abandonar o parque de campismo, deixando a sua unidade de campismo ou ve\u00edculo no local, \u00e9 obrigado a informar o servi\u00e7o de rece\u00e7\u00e3o. A dire\u00e7\u00e3o do parque de campismo pode aceitar a aus\u00eancia nas condi\u00e7\u00f5es acordadas em fun\u00e7\u00e3o das circunst\u00e2ncias ou, caso contr\u00e1rio, exigir que o cliente abandone o parque com todos os seus pertences. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os clientes que utilizem autocaravanas para as suas desloca\u00e7\u00f5es e que deixem o campo livre durante estes per\u00edodos devem informar-nos para evitar ocupar o seu espa\u00e7o por engano.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o \u00e9 permitida a ocupa\u00e7\u00e3o de espa\u00e7os manifestamente desproporcionados em rela\u00e7\u00e3o ao n\u00famero de pessoas que os utilizam em \u00e1reas n\u00e3o parceladas. Considera-se desproporcionada qualquer \u00e1rea superior \u00e0 correspondente ao n\u00famero de campistas, abrigos e\/ou ve\u00edculos, no caso de ser parcelada. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">O cliente deve pagar o pre\u00e7o dos servi\u00e7os facturados e a dire\u00e7\u00e3o do parque de campismo pode exigir o pagamento a qualquer momento.&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As tarifas de estadia s\u00e3o calculadas por dia, terminando 24 horas ap\u00f3s o check-in para o campismo e \u00e0s 12h00 para os bungalows. <\/span><span style=\"font-weight: 400;\">A tua estadia termina 24 horas ap\u00f3s o check-in para campismo e \u00e0s 12h00 para bungalows.<\/span><span style=\"font-weight: 400;\"> Se o cliente n\u00e3o abandonar a \u00e1rea ocupada nessa altura, ser\u00e1 considerado um prolongamento da estadia por mais um dia. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os clientes que pretendam partir antes da abertura do servi\u00e7o de rece\u00e7\u00e3o devem liquidar a sua conta no dia anterior.&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Considera v\u00e1lidos os pre\u00e7os afixados na Rece\u00e7\u00e3o.&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As tarifas de entrada ou de estadia incluem os seguintes servi\u00e7os para o cliente:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Kit de primeiros socorros&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Consumo de \u00e1gua pot\u00e1vel&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ilumina\u00e7\u00e3o p\u00fablica&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Tomadas el\u00e9ctricas nos lavat\u00f3rios&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Chuveiros, lavat\u00f3rios e casas de banho<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Drenagem de \u00e1guas cinzentas e negras<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Lavat\u00f3rios e lavandarias&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Recolha de res\u00edduos&nbsp;<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n<p><b>ENTRADA DE ANIMAIS<\/b><\/p>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00c9 proibida a entrada de animais manifestamente perigosos ou que causem inc\u00f3modo aos campistas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Para qualquer animal dom\u00e9stico cuja entrada seja autorizada, deve ser feito um registo de entrada.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">A documenta\u00e7\u00e3o sanit\u00e1ria pertinente deve estar em ordem.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Qualquer um&nbsp;  animal,&nbsp;  cujo&nbsp;  entrada&nbsp;  faia&nbsp;  tem sido&nbsp;  admitido&nbsp;  por&nbsp;  o&nbsp;  servi\u00e7os&nbsp;  de&nbsp;  rece\u00e7\u00e3o,&nbsp;  deve&nbsp;  permanece&nbsp;  em&nbsp;  todos&nbsp;  tempo&nbsp;  juntamente com&nbsp;  o teu&nbsp;  propriet\u00e1rio&nbsp;  respons\u00e1vel,&nbsp;  amarrado&nbsp;  y&nbsp;  sob&nbsp;  o teu&nbsp;  N\u00e3o podes deix\u00e1-los sozinhos. N\u00e3o \u00e9 permitido deixar nenhum animal sozinho no interior dos bungalows. <\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">O&nbsp;  propriet\u00e1rio&nbsp;  cuida de&nbsp;  de&nbsp;  que&nbsp;  sobre&nbsp;  animal&nbsp;  vai para&nbsp;  o teu&nbsp;  fun\u00e7\u00f5es&nbsp;  higi\u00e9nico&nbsp;  em&nbsp;  o&nbsp;  Os locais estabelecidos e para remover os excrementos. Se for inevit\u00e1vel, a urina deve ser dilu\u00edda com \u00e1gua para garantir a salubridade da via e dos espa\u00e7os p\u00fablicos, evitando a degrada\u00e7\u00e3o do mobili\u00e1rio p\u00fablico. <\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Os c\u00e3es classificados como &#8220;potencialmente perigosos&#8221; devem tamb\u00e9m usar a\u00e7aime e trela n\u00e3o extens\u00edvel, e o seu propriet\u00e1rio deve possuir uma licen\u00e7a especial e o respetivo seguro.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Por raz\u00f5es sanit\u00e1rias, n\u00e3o s\u00e3o permitidos animais na zona da piscina, nas casas de banho, na caixa de primeiros socorros e na loja do parque de campismo.&nbsp;&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">O&nbsp;  propriet\u00e1rio&nbsp;  de&nbsp;  animal&nbsp;  em&nbsp;  responsabiliza-te&nbsp;  ambos&nbsp;  civil&nbsp;  como&nbsp;  economicamente&nbsp;  de&nbsp;  todos&nbsp;  o&nbsp;  danos&nbsp;  que&nbsp;  o animal pode causar danos a pessoas, bens e instala\u00e7\u00f5es.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Gostas?&nbsp;  exce\u00e7\u00e3o&nbsp;  a&nbsp;  lo&nbsp;  estabelecido&nbsp;  em&nbsp;  este&nbsp;  sec\u00e7\u00e3o,&nbsp;  em&nbsp;  autoriza&nbsp;  o&nbsp;  entrada&nbsp;  de&nbsp;  c\u00e3es&nbsp;  guia&nbsp;  que&nbsp;  acompanha&nbsp;  pessoas com defici\u00eancia visual.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">O teu animal de estima\u00e7\u00e3o deve usar a faixa de identifica\u00e7\u00e3o na coleira ou no arn\u00eas para nos permitir contactar o respons\u00e1vel.&nbsp;&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Os propriet\u00e1rios devem evitar perturbar as parcelas vizinhas.&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">A documenta\u00e7\u00e3o pode ser exigida em qualquer altura durante a estadia.&nbsp;<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n<p><b>TR\u00c1FEGO DE VE\u00cdCULOS<\/b><\/p>\n<p><span style=\"font-weight: 400;\">No interior do parque de campismo, os ve\u00edculos devem limitar a sua velocidade a 5 km\/h. A utiliza\u00e7\u00e3o de ve\u00edculos \u00e9 limitada ao acesso e \u00e0 sa\u00edda dos clientes. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 proibida a circula\u00e7\u00e3o de todos os tipos de ve\u00edculos a motor durante as horas de sil\u00eancio e de repouso estabelecidas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 proibida a utiliza\u00e7\u00e3o de buzinas de ve\u00edculos, exceto em casos de for\u00e7a maior.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os clientes devem estacionar os seus ve\u00edculos nos parques de estacionamento e\/ou parcelas designadas para o efeito, evitando sempre estacionar nas vias interiores ou em zonas que dificultem o acesso de ve\u00edculos e pessoas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ap\u00f3s o in\u00edcio do per\u00edodo de sil\u00eancio, os ve\u00edculos que regressam ao parque de campismo n\u00e3o s\u00e3o autorizados a entrar na zona de campismo. Em vez disso, podem estacionar no parque de estacionamento na zona da rece\u00e7\u00e3o, se houver lugares dispon\u00edveis. Quando o parque de estacionamento estiver cheio, n\u00e3o ser\u00e1 permitida a entrada ou o estacionamento de ve\u00edculos no interior do parque de campismo.  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n<p><b>SISTEMAS DE SOM<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 proibido ouvir m\u00fasica atrav\u00e9s do equipamento de bordo, do equipamento port\u00e1til ou dos dispositivos m\u00f3veis. A audi\u00e7\u00e3o de m\u00fasica ou r\u00e1dio deve ser feita atrav\u00e9s de equipamento de audi\u00e7\u00e3o pessoal (auscultadores). <\/span><\/p>\n<p><span style=\"font-weight: 400;\">O equipamento de televis\u00e3o ou r\u00e1dio nas tendas, caravanas ou autocaravanas deve ser mantido a um n\u00edvel de volume m\u00ednimo para n\u00e3o perturbar os campos ocupados mais pr\u00f3ximos.<\/span><\/p>\n<p><b>&nbsp;<\/b><\/p>\n<p><b>OBRIGA\u00c7\u00d5ES DOS CLIENTES<\/b><\/p>\n<p><span style=\"font-weight: 400;\">As pessoas alojadas devem respeitar as seguintes obriga\u00e7\u00f5es:<\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Aceita e cumpre o Regulamento Interno do estabelecimento.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Respeitar as regras b\u00e1sicas de seguran\u00e7a, conviv\u00eancia, moral e higiene para a boa utiliza\u00e7\u00e3o do estabelecimento, especialmente durante a atividade de campismo, onde se exige a preserva\u00e7\u00e3o do civismo, da sa\u00fade e do respeito m\u00fatuo. N\u00e3o ser\u00e1 tolerado o comportamento de pessoas sob o efeito de \u00e1lcool ou drogas que alterem ou possam alterar a conviv\u00eancia no parque de campismo. <\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Utiliza\u00e7\u00e3o adequada dos sistemas de controlo e identifica\u00e7\u00e3o de pessoas ou ve\u00edculos estabelecidos para cada situa\u00e7\u00e3o.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Respeita a flora, a fauna e todas as instala\u00e7\u00f5es do parque de campismo, fazendo uma utiliza\u00e7\u00e3o adequada das mesmas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Informar a Dire\u00e7\u00e3o dos casos conhecidos de doen\u00e7as contagiosas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Abandonar o parque de campismo no final do hor\u00e1rio acordado, exceto se tiver sido acordado um prolongamento entre a Empresa e o cliente.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Mant\u00e9m o parque de campismo nas mesmas condi\u00e7\u00f5es em que se encontrava \u00e0 chegada.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Utiliza as instala\u00e7\u00f5es designadas para lavar os utens\u00edlios de cozinha e a roupa.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Colabora na separa\u00e7\u00e3o dos res\u00edduos s\u00f3lidos nos contentores correspondentes:<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Informa imediatamente o pessoal do parque de campismo de qualquer acidente ou emerg\u00eancia, para que sejam tomadas as medidas necess\u00e1rias.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Os clientes com caravanas ou autocaravanas de longa dura\u00e7\u00e3o devem ter um seguro que cubra inc\u00eandio, explos\u00e3o, raios, garantias alargadas, danos causados pela \u00e1gua, roubo e furto (incluindo bens dom\u00e9sticos) e responsabilidade civil.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Toma as devidas precau\u00e7\u00f5es para proteger os seus bens e interesses.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Trazer e mostrar os elementos de identifica\u00e7\u00e3o pessoal fornecidos pela Dire\u00e7\u00e3o a pedido do pessoal do parque de campismo.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">&nbsp;Utiliza&nbsp;  cabos de extens\u00e3o&nbsp;  de&nbsp;  alimenta\u00e7\u00e3o&nbsp;  el\u00e9trico&nbsp;  constru\u00eddo&nbsp;  com&nbsp;  cabo tipo mangueira e ficha \u00e0 prova de intemp\u00e9ries.&nbsp;  O&nbsp;  cabo&nbsp;  a&nbsp;  usa&nbsp;  deve&nbsp;  ser&nbsp;  cont\u00ednua,&nbsp;  sem&nbsp;  emendas e extens\u00f5es de interliga\u00e7\u00e3o.&nbsp;  Evitar os &#8220;enxames&nbsp;  de&nbsp;  cabos&nbsp;  liga a uma tomada el\u00e9ctrica.  &nbsp;  O&nbsp;  cablagem&nbsp;  y&nbsp;  Os acess\u00f3rios devem estar em conformidade com os regulamentos do R.B.T.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Para&nbsp;  sobre&nbsp;  ilumina\u00e7\u00e3o&nbsp;  fora&nbsp;  usa&nbsp;  dispositivos&nbsp;  com&nbsp;  grau&nbsp;  de&nbsp;  prote\u00e7\u00e3o&nbsp;  IP65,&nbsp;  com&nbsp;  l\u00e2mpadas&nbsp;  conduzido&nbsp;  de&nbsp;  sob&nbsp;  consumo&nbsp;  (m\u00e1ximo&nbsp;  8&nbsp;  watts)&nbsp;  y&nbsp;  cabo&nbsp;  cabo de extens\u00e3o&nbsp;  de acordo com&nbsp;  tipo&nbsp;  descrito no aparelho anterior.&nbsp;  Desliga&nbsp;  a sua ilumina\u00e7\u00e3o exterior a partir da meia-noite.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">As tomadas m\u00faltiplas devem permanecer cobertas no interior do avan\u00e7o e a uma altura superior a 30 cm do solo.&nbsp;&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">O&nbsp;  caravanas&nbsp;  o&nbsp;  autocaravanas&nbsp;  em&nbsp;  regime&nbsp;  de&nbsp;  fica&nbsp;  longo&nbsp;  y&nbsp;  em&nbsp;  aus\u00eancia&nbsp;  de&nbsp;  o teu&nbsp;  propriet\u00e1rios,&nbsp;  estar\u00e1 dispon\u00edvel em&nbsp;  estacionado&nbsp;  em&nbsp;  sobre&nbsp;  s\u00edtio&nbsp;  y&nbsp;  condi\u00e7\u00f5es&nbsp;  t\u00e9cnicas&nbsp;  estabelecido&nbsp;  por&nbsp;  o&nbsp;  Endere\u00e7o;&nbsp;  o&nbsp;  progresso&nbsp;  estar\u00e1 dispon\u00edvel em&nbsp;  desmantelado&nbsp;  y&nbsp;  todos&nbsp;  o&nbsp;  pertences&nbsp;  complementares&nbsp;  de&nbsp;  Acampamento guardado no interior do alojamento.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Trata os empregados de forma educada e com respeito.&nbsp;<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n<p><b>PROIBI\u00c7\u00d5ES<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 proibido:<\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Perturba o descanso do resto dos campistas.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Praticar jogos ou desportos que possam perturbar os outros campistas, bem como qualquer atividade colectiva de qualquer tipo sem a autoriza\u00e7\u00e3o expressa da Dire\u00e7\u00e3o.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Entra na rece\u00e7\u00e3o ou no bar-restaurante com o tronco descoberto.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Aceder descal\u00e7o \u00e0s casas de banho, aos lavabos, \u00e0 rece\u00e7\u00e3o ou ao bar-restaurante.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Acender churrascos ou qualquer tipo de fogo em todo o parque de campismo. Exceto nas churrasqueiras do parque de campismo em per\u00edodos de baixo risco de inc\u00eandio. &nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Consumo de estupefacientes ou similares.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Realiza\u00e7\u00e3o de &#8220;botellones&#8221;.&nbsp;&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">A coloca\u00e7\u00e3o de elementos fixos, tais como: recintos ou estruturas para gerar sombra.<\/span>&nbsp;<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">V\u00ea&nbsp;  permite&nbsp;  o&nbsp;  localiza\u00e7\u00e3o&nbsp;  de&nbsp;  caravanas&nbsp;  o&nbsp;  autocaravanas&nbsp;  com&nbsp;  o teu&nbsp;  respetivo&nbsp;  progresso&nbsp;  pr\u00f3prio&nbsp;  de&nbsp;  fabrico&nbsp;  para esse fim e utiliza\u00e7\u00e3o.&nbsp;&nbsp;<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00c9 proibido erguer estruturas met\u00e1licas ou de madeira para cobrir \u00e1reas do lote, \u00e0 escolha do campista.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">N\u00e3o&nbsp;  em&nbsp;  permite&nbsp;  cobre&nbsp;  todos&nbsp;  a parcela com guarda-s\u00f3is, sombras, toldos e\/ou similares.&nbsp;  V\u00ea&nbsp;  permite&nbsp;  o&nbsp;  instala\u00e7\u00e3o&nbsp;  de&nbsp;  a&nbsp;  apenas tenda de cozinha com dimens\u00f5es m\u00e1ximas de 3 x 2 mts.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">O&nbsp;  ch\u00e3o&nbsp;  que&nbsp;  ocupa&nbsp;  pr\u00e9-visualiza\u00e7\u00e3o+exibi\u00e7\u00e3o+loja&nbsp;  cozinha&nbsp;  pode ser coberto com uma rede de recolha de frutos para permitir o arejamento e a drenagem adequados do solo.&nbsp;  O&nbsp;  descansa&nbsp;  de&nbsp;  o&nbsp;  o enredo deve&nbsp;  permanece&nbsp;  areja para a boa conserva\u00e7\u00e3o do solo.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Utiliza\u00e7\u00e3o de aparelhos dom\u00e9sticos em funcionamento cont\u00ednuo (por exemplo, frigor\u00edficos, aparelhos de ar condicionado) que, devido ao seu n\u00edvel de ru\u00eddo, perturbam o sono dos campistas pr\u00f3ximos.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Transportar armas ou objectos suscept\u00edveis de provocar acidentes.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Deixar o lixo fora dos contentores previstos para o efeito.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Guardar o vestu\u00e1rio em locais n\u00e3o autorizados.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Abertura de valas ou qualquer tipo de terraplanagem, bem como desloca\u00e7\u00e3o de marcos de fronteira.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Plantar plantas ou colher frutos de \u00e1rvores ou arbustos no parque de campismo sem autoriza\u00e7\u00e3o pr\u00e9via.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00c9 proibido instalar cordas ou fios entre duas ou mais \u00e1rvores, postes de ilumina\u00e7\u00e3o ou qualquer outro elemento fixo. \u00c9 igualmente proibido pregar qualquer tipo de elemento ou objeto aos elementos acima referidos ou fixar qualquer objeto aos mesmos. <\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Pregar espig\u00f5es ou qualquer outro elemento com mais de 30 cm de comprimento (deve ser dada especial aten\u00e7\u00e3o aos tubos el\u00e9ctricos e de \u00e1gua).&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Trazer para o parque de campismo pessoas que n\u00e3o estejam alojadas no parque de campismo, tal como descrito na pol\u00edtica de admiss\u00e3o.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00c9 proibido aos campistas e\/ou aos animais realizar actividades higi\u00e9nicas fora das zonas estabelecidas para o efeito.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Estacionar ve\u00edculos fora dos lugares de estacionamento autorizados.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Lavagem de ve\u00edculos ou qualquer opera\u00e7\u00e3o de repara\u00e7\u00e3o ou manuten\u00e7\u00e3o que possa causar danos ao ambiente.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Utiliza ve\u00edculos (por exemplo, motas ou trotinetas el\u00e9ctricas) para passear ou brincar dentro do parque de campismo.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Lavar utens\u00edlios ou roupa em fontes de \u00e1gua.&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Faz liga\u00e7\u00f5es fixas \u00e0s tomadas de \u00e1gua comuns.&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Utiliza&nbsp;  cabos&nbsp;  o&nbsp;  acess\u00f3rios&nbsp;  el\u00e9trico&nbsp;  para&nbsp;  realizar&nbsp;  tomadas&nbsp;  de&nbsp;  correntes,&nbsp;  que n\u00e3o as normalizadas.&nbsp;  Os cabos n\u00e3o devem ser unidos e as extens\u00f5es m\u00faltiplas n\u00e3o devem ser unidas.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Instala linhas el\u00e9ctricas para a ilumina\u00e7\u00e3o exterior de caravanas ou tendas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">A venda de qualquer artigo no interior do parque de campismo.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Monta ou desmonta unidades de campismo durante as horas de sil\u00eancio.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">A utiliza\u00e7\u00e3o dos servi\u00e7os fora do hor\u00e1rio de funcionamento estabelecido.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Realizar qualquer a\u00e7\u00e3o que possa prejudicar a propriedade, a higiene e o aspeto do parque de campismo.&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">A&nbsp;  o&nbsp;  clientes&nbsp;  com&nbsp;  caravanas&nbsp;  o&nbsp;  autocaravanas&nbsp;  em&nbsp;  regime&nbsp;  de&nbsp;  parque de estacionamento&nbsp;  prolongado,&nbsp;  deixa&nbsp;  bens dom\u00e9sticos,&nbsp;  equipamento&nbsp;  de&nbsp;  imagem sonora,&nbsp;  bicicletas,&nbsp;  etc.,&nbsp;  em&nbsp;  geral&nbsp;  de um determinado valor e fora do equipamento pr\u00f3prio do fabricante.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">A utiliza\u00e7\u00e3o de&nbsp;  recipientes&nbsp;  de&nbsp;  g\u00e1s&nbsp;  butano&nbsp;  dom\u00e9stico&nbsp;  (13&nbsp;  Kg),&nbsp;  a menos que fa\u00e7am parte da instala\u00e7\u00e3o de&nbsp;  s\u00e9rie&nbsp;  de&nbsp;  fabricante&nbsp;  de&nbsp;  alojamento&nbsp;  y&nbsp;  tem o certificado de instala\u00e7\u00e3o atualizado correspondente.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Esvazia as casas de banho qu\u00edmicas das caravanas e autocaravanas nas sanitas, utilizando a instala\u00e7\u00e3o de elimina\u00e7\u00e3o de res\u00edduos adequada.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">A entrada de ve\u00edculos comerciais.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Oculta\u00e7\u00e3o intencional de conceitos de fatura\u00e7\u00e3o ou de dados de filia\u00e7\u00e3o.&nbsp;&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Fumar em todas as instala\u00e7\u00f5es de uso coletivo do parque de campismo.&nbsp; <\/span><span style=\"font-weight: 400;\">Tamb\u00e9m \u00e9 proibido fumar no interior dos bungalows.<\/span><span style=\"font-weight: 400;\">.&nbsp;  Em&nbsp;  o&nbsp;  espa\u00e7os&nbsp;  aberto&nbsp;  de&nbsp;  acampamento&nbsp;  em&nbsp;  podes&nbsp;  fuma,&nbsp;  sempre&nbsp;  y&nbsp;  quando&nbsp;  em&nbsp;  dispon\u00edvel em&nbsp;  de&nbsp;  contentor&nbsp;  o&nbsp;  cinzeiro&nbsp;  adequado&nbsp;  para&nbsp;  sobre&nbsp;  dep\u00f3sito&nbsp;  e apaga as pontas de cigarro.&nbsp;  V\u00ea&nbsp;  proibido&nbsp;  lan\u00e7a&nbsp;  o&nbsp;  apaga os cigarros diretamente no ch\u00e3o.&nbsp;<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n<p><b>SAN\u00c7\u00d5ES<\/b><\/p>\n<p><span style=\"font-weight: 400;\">O incumprimento das obriga\u00e7\u00f5es, proibi\u00e7\u00f5es ou regras estipuladas no presente regulamento constitui motivo suficiente para a rescis\u00e3o unilateral do contrato de alojamento, sem que o infrator tenha direito a qualquer indemniza\u00e7\u00e3o. O campista que violar qualquer das proibi\u00e7\u00f5es estabelecidas, n\u00e3o cumprir as instru\u00e7\u00f5es constantes do presente regulamento, n\u00e3o respeitar as regras b\u00e1sicas de educa\u00e7\u00e3o e conviv\u00eancia social e, em geral, n\u00e3o respeitar os princ\u00edpios fundamentais da vida civilizada, ser\u00e1 formalmente convidado a abandonar as instala\u00e7\u00f5es. Caso n\u00e3o cumpra este convite, poder\u00e1 ser expulso do parque de campismo por decis\u00e3o da dire\u00e7\u00e3o do parque e\/ou da autoridade competente, de acordo com o disposto na legisla\u00e7\u00e3o tur\u00edstica em vigor, sem preju\u00edzo das san\u00e7\u00f5es pecuni\u00e1rias e outras que a autoridade competente possa aplicar.  <\/span><\/p>\n<p><b>&nbsp;<\/b><\/p>\n<p><b>INFORMA\u00c7\u00d5ES&nbsp;<\/b><\/p>\n<p><span style=\"font-weight: 400;\">No Gabinete de Rece\u00e7\u00e3o do parque de campismo, est\u00e3o dispon\u00edveis para os clientes todas as informa\u00e7\u00f5es regulamentares, bem como quaisquer outras informa\u00e7\u00f5es consideradas relevantes para o campista. Al\u00e9m disso, o utilizador tem a possibilidade de manifestar as suas opini\u00f5es, sugest\u00f5es, queixas ou reclama\u00e7\u00f5es relacionadas com a qualidade dos servi\u00e7os e instala\u00e7\u00f5es. Para tal, podes utilizar os mecanismos estabelecidos no Gabinete de Rece\u00e7\u00e3o, que incluem:  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Comunica\u00e7\u00e3o verbal com os empregados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Comunica\u00e7\u00e3o escrita para o endere\u00e7o eletr\u00f3nico info@campingarribesdelduero.com<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Utiliza\u00e7\u00e3o de formul\u00e1rios de reclama\u00e7\u00e3o.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7466f98 elementor-widget elementor-widget-heading\" data-id=\"7466f98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">RESPONSABILIDADE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d93cf15 elementor-widget elementor-widget-text-editor\" data-id=\"d93cf15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">O Camping declina qualquer responsabilidade por furtos e danos derivados dos mesmos, bem como por qualquer tipo de furto que possa ser sofrido pelos clientes, aos quais se pede a sua colabora\u00e7\u00e3o neste sentido, recomendando-lhes que tomem as precau\u00e7\u00f5es adequadas para proteger os seus pertences e interesses. A empresa tamb\u00e9m n\u00e3o assume qualquer responsabilidade por danos causados por outros clientes, terceiros ou acontecimentos naturais, incluindo incidentes atmosf\u00e9ricos. <\/span><\/p><p><span style=\"font-weight: 400;\">Em caso de condi\u00e7\u00f5es climat\u00e9ricas adversas, como ventos fortes ou chuva cont\u00ednua, espera-se que os clientes cuidem dos seus pertences, considerando mesmo a possibilidade de abandonar o acampamento, se necess\u00e1rio. A empresa disp\u00f5e de um seguro de responsabilidade civil para cobrir os riscos associados \u00e0 presta\u00e7\u00e3o dos seus servi\u00e7os. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a8caa8 elementor-widget elementor-widget-spacer\" data-id=\"1a8caa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff666d5 elementor-widget elementor-widget-text-editor\" data-id=\"ff666d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">*O Decreto 9\/2017, de 15 de junho, que regula os estabelecimentos de alojamento sob a forma de campismo na Comunidade de Castela e Le\u00e3o e a Lei 14\/2010, de 9 de dezembro, de Turismo de Castela e Le\u00e3o, regula nos artigos 38 e 39 os estabelecimentos de alojamento sob a forma de campismo, como um tipo de estabelecimentos de alojamento tur\u00edstico.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee8e137 elementor-widget elementor-widget-spacer\" data-id=\"ee8e137\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>regulamento interno do Camping arribes del duero Registo de Campismo n.\u00ba: 37\/0023. Categoria: 3 estrelas. POL\u00cdTICA DE ADMISS\u00c3O E RETEN\u00c7\u00c3O O&nbsp; acesso&nbsp; a&nbsp; este&nbsp; acampamento&nbsp; de&nbsp; turismo&nbsp; \u00e9&nbsp; livre,&nbsp; sem&nbsp; mais&nbsp; restri\u00e7\u00f5es&nbsp; que&nbsp; o&nbsp; derivados&nbsp; de&nbsp; o&nbsp; leis* e estes regulamentos.&nbsp; N\u00e3o \u00e9 permitida a entrada a pessoas que tenham sido anteriormente expulsas por viola\u00e7\u00e3o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":889,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_joinchat":[],"footnotes":""},"class_list":["post-1970","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/campingarribesdelduero.com\/pt-pt\/wp-json\/wp\/v2\/pages\/1970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campingarribesdelduero.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/campingarribesdelduero.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/campingarribesdelduero.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/campingarribesdelduero.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=1970"}],"version-history":[{"count":6,"href":"https:\/\/campingarribesdelduero.com\/pt-pt\/wp-json\/wp\/v2\/pages\/1970\/revisions"}],"predecessor-version":[{"id":6365,"href":"https:\/\/campingarribesdelduero.com\/pt-pt\/wp-json\/wp\/v2\/pages\/1970\/revisions\/6365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campingarribesdelduero.com\/pt-pt\/wp-json\/wp\/v2\/media\/889"}],"wp:attachment":[{"href":"https:\/\/campingarribesdelduero.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=1970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}