{"id":4912,"date":"2024-12-16T14:12:05","date_gmt":"2024-12-16T13:12:05","guid":{"rendered":"https:\/\/campingarribesdelduero.com\/reservations\/"},"modified":"2025-03-16T14:46:18","modified_gmt":"2025-03-16T13:46:18","slug":"reservations","status":"publish","type":"page","link":"https:\/\/campingarribesdelduero.com\/en\/reservations\/","title":{"rendered":"RESERVATIONS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4912\" class=\"elementor elementor-4912 elementor-4179\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-175a3cb4 e-flex e-con-boxed e-con e-parent\" data-id=\"175a3cb4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5b4fc3 elementor-widget elementor-widget-shortcode\" data-id=\"a5b4fc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n    <div class=\"TMrPlanPlugin_BarraIdiomas\">\n        <a href=\"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/pages\/4912?id_idioma=0\" title=\"Spanish\" id=\"TMrPlanPlugin_BarraIdiomas_0\">\n        <img decoding=\"async\" class=\"TMrPlanPlugin_BarraIdiomas_Check\" alt=\"Spanish\" src=\"https:\/\/campingarribesdelduero.com\/wp-content\/plugins\/misterplan\/\/assets\/images\/languages\/bandera_0_blanco.png\">\n    <\/a>\n        <a href=\"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/pages\/4912?id_idioma=1\" title=\"English\" id=\"TMrPlanPlugin_BarraIdiomas_1\">\n        <img decoding=\"async\" class=\"\" alt=\"English\" src=\"https:\/\/campingarribesdelduero.com\/wp-content\/plugins\/misterplan\/\/assets\/images\/languages\/bandera_1_blanco.png\">\n    <\/a>\n        <a href=\"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/pages\/4912?id_idioma=2\" title=\"Portuguese\" id=\"TMrPlanPlugin_BarraIdiomas_2\">\n        <img decoding=\"async\" class=\"\" alt=\"Portuguese\" src=\"https:\/\/campingarribesdelduero.com\/wp-content\/plugins\/misterplan\/\/assets\/images\/languages\/bandera_2_blanco.png\">\n    <\/a>\n        <a href=\"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/pages\/4912?id_idioma=3\" title=\"French\" id=\"TMrPlanPlugin_BarraIdiomas_3\">\n        <img decoding=\"async\" class=\"\" alt=\"French\" src=\"https:\/\/campingarribesdelduero.com\/wp-content\/plugins\/misterplan\/\/assets\/images\/languages\/bandera_3_blanco.png\">\n    <\/a>\n        <a href=\"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/pages\/4912?id_idioma=4\" title=\"Italian\" id=\"TMrPlanPlugin_BarraIdiomas_4\">\n        <img decoding=\"async\" class=\"\" alt=\"Italian\" src=\"https:\/\/campingarribesdelduero.com\/wp-content\/plugins\/misterplan\/\/assets\/images\/languages\/bandera_4_blanco.png\">\n    <\/a>\n        <a href=\"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/pages\/4912?id_idioma=5\" title=\"German\" id=\"TMrPlanPlugin_BarraIdiomas_5\">\n        <img decoding=\"async\" class=\"\" alt=\"German\" src=\"https:\/\/campingarribesdelduero.com\/wp-content\/plugins\/misterplan\/\/assets\/images\/languages\/bandera_5_blanco.png\">\n    <\/a>\n        <a href=\"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/pages\/4912?id_idioma=6\" title=\"Catalan\" id=\"TMrPlanPlugin_BarraIdiomas_6\">\n        <img decoding=\"async\" class=\"\" alt=\"Catalan\" src=\"https:\/\/campingarribesdelduero.com\/wp-content\/plugins\/misterplan\/\/assets\/images\/languages\/bandera_6_blanco.png\">\n    <\/a>\n        <a href=\"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/pages\/4912?id_idioma=7\" title=\"Galician\" id=\"TMrPlanPlugin_BarraIdiomas_7\">\n        <img decoding=\"async\" class=\"\" alt=\"Galician\" src=\"https:\/\/campingarribesdelduero.com\/wp-content\/plugins\/misterplan\/\/assets\/images\/languages\/bandera_7_blanco.png\">\n    <\/a>\n        <a href=\"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/pages\/4912?id_idioma=8\" title=\"Basque\" id=\"TMrPlanPlugin_BarraIdiomas_8\">\n        <img decoding=\"async\" class=\"\" alt=\"Basque\" src=\"https:\/\/campingarribesdelduero.com\/wp-content\/plugins\/misterplan\/\/assets\/images\/languages\/bandera_8_blanco.png\">\n    <\/a>\n    <\/div><!-- MISTERPLAN PLUGIN 1.1.45-->\n<!-- MISTERPLAN PLUGIN MOTOR TIPO 1 ID ELEMENTO 584074 DESTINO 1 PV 8648-->\n    <script nowprocket async type=\"text\/javascript\" src=\"https:\/\/www.mrplan.es\/experiencias\/modulos\/TWidget\/lib\/TWidgetInc.php?id_casa=584074&source_plugin=MrPlanPlugin&web_plugin=https%3A%2F%2Fcampingarribesdelduero.com%2Fen%2Freservations%2F&cod_habitacion=571136-143\"><\/script>\n<div id=\"MrPlanPlugin_MotorScript\"><\/div>\n<div class=\"MrPlanPlugin_MotorContainer MrPlanPlugin_MotorContainer_1\" >\n\n\t<div nowprocket id=\"TEwsBuscadorB-1-1-584074-\" \n\t\tclass=\"TEwsWidgetInc capa_izq ancho_total\"\n\t\tTEws_id_idioma=\"0\"\n        url_confirmacion=\"https:\/\/campingarribesdelduero.com\/confirmacion-de-reserva\/\"\t\t\n        TEws_id_elemento=\"584074\"\n        TEws_tipo_elemento=\"1\"\n        TEws_Hash=\"4c56a304f218bc5e408e6e5926c5f25c99382b79\"\n        TEws_id_destino=\"1\"\n        TEws_id_puntoventa=\"8648\"\n        TEws_autoload=\"0\"\n        TEws_fecha_ini=\"\"\n        TEws_n_noches=\"1\"\n        TEws_visualFilterOccupancy=\"\" \n        w_contenido=\"completa\"\n\t\tBudgetV=\"2\" \n        mini_preview_V=\"2\" \n        TEws_onSearch=\"\" \n        TEws_version=\"12\" \n        TEws_tipo_widget=\"1\" \n        BV7_tipo_inicio=\"0\" \n        BV7_cambio_inicio=\"0\" \n        TEws_quitar_cabecera=\"0\" \n        TEws_iniciar_cerrado=\"0\" \n        TEws_bus_texto=\"0\" \n        TEws_sel_dispo=\"1\" \n        TEws_form_contacto=\"0\"  \n        TEws_result_in_esl=\"0\" \n        TEws_result_in_ext=\"0\" \n        TEws_cerrar_buscar=\"0\" \n        TEws_ver_resto_casas=\"0\" \n        TEws_activar_mas_menos=\"1\" \n        TEws_posicion=\"original\" \n        TEws_formato=\"2\" \n        TEws_formato_ficha=\"10\" \n        TEws_CoreSearch_V=\"7\"  \n        TEws_id_categoria=\"0\" \n        TEws_modo=\"RES\"  \n        TEws_radio=\"0\"\n        TEsw_filtro_exp=\"\" \n        TEws_filtro_casa=\"\" \n                TEws_cod_habitacion=\"584074-0\"\n                TEwsResultadoCoreSearch=\"TEwsResultCoreSearch-1-1-584074-\" \n        alt=\"MisterPlan  - Powered by RuralGest  - http:\/\/www.misterplan.es\" \n\t\ttitle_NO=\"MisterPlan  - Powered by RuralGest \"\n\t>\n        <div class=\"TMrPlanPlugin_Loading\">\n            <img decoding=\"async\" src=\"https:\/\/campingarribesdelduero.com\/wp-content\/plugins\/misterplan\/assets\/images\/loading.svg\">\n        <\/div>\n    <\/div>\n    <div id=\"TEwsResultCoreSearch-1-1-584074-\" class=\"capa_izq TEwsBuscador_Experiencias_evnt\" style=\"width: 100%; margin-top: 20px;\" ><\/div> \n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":3615,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_joinchat":[],"footnotes":""},"class_list":["post-4912","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/pages\/4912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/comments?post=4912"}],"version-history":[{"count":17,"href":"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/pages\/4912\/revisions"}],"predecessor-version":[{"id":6313,"href":"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/pages\/4912\/revisions\/6313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/media\/3615"}],"wp:attachment":[{"href":"https:\/\/campingarribesdelduero.com\/en\/wp-json\/wp\/v2\/media?parent=4912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}